{"id":67,"date":"2021-01-14T16:23:52","date_gmt":"2021-01-14T16:23:52","guid":{"rendered":"https:\/\/www.thetirelab.com\/mag\/?p=67"},"modified":"2022-01-29T12:56:03","modified_gmt":"2022-01-29T12:56:03","slug":"so-messen-sie-das-reifenprofil-richtig-und-einfach","status":"publish","type":"post","link":"https:\/\/reifenlab.de\/mag\/so-messen-sie-das-reifenprofil-richtig-und-einfach\/","title":{"rendered":"So messen Sie das Reifenprofil richtig und einfach"},"content":{"rendered":"\n<p>W\u00e4hrend der Fahrt nutzt sich die Oberfl\u00e4che der Lauffl\u00e4che, je nach verwendeter Mischung, unterschiedlich schnell ab, sodass der Reifen nicht mehr den gesetzlichen Normen entspricht. Diese Normen wurden jedoch aus gutem Grund eingef\u00fchrt &#8211; ein abgenutzter Reifen hat eine schlechtere Haftung, einen l\u00e4ngeren Bremsweg und ist anf\u00e4lliger f\u00fcr Aquaplaning, daher ist die regelm\u00e4\u00dfige Kontrolle der Lauffl\u00e4che eine absolut unverzichtbare Routine f\u00fcr jeden Fahrer. Fassen wir also zusammen, wie wir die Tiefe des Reifenprofils zu Hause bestimmen k\u00f6nnen.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_69_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\">\u2630<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a9814064b408\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9814064b408\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/reifenlab.de\/mag\/so-messen-sie-das-reifenprofil-richtig-und-einfach\/#Was_ist_vor_der_eigentlichen_Messung_zu_tun\" title=\"Was ist vor der eigentlichen Messung zu tun?\">Was ist vor der eigentlichen Messung zu tun?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/reifenlab.de\/mag\/so-messen-sie-das-reifenprofil-richtig-und-einfach\/#Laufflachenverschleisindikator_TWITread_Wear_indicator\" title=\"Lauffl\u00e4chenverschlei\u00dfindikator (TWI=Tread Wear indicator)\">Lauffl\u00e4chenverschlei\u00dfindikator (TWI=Tread Wear indicator)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/reifenlab.de\/mag\/so-messen-sie-das-reifenprofil-richtig-und-einfach\/#Numerische_Verschleisindikator\" title=\"Numerische Verschlei\u00dfindikator\">Numerische Verschlei\u00dfindikator<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/reifenlab.de\/mag\/so-messen-sie-das-reifenprofil-richtig-und-einfach\/#Tiefenmesser\" title=\"Tiefenmesser\">Tiefenmesser<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/reifenlab.de\/mag\/so-messen-sie-das-reifenprofil-richtig-und-einfach\/#Messung_mit_Munzen\" title=\"Messung mit M\u00fcnzen\">Messung mit M\u00fcnzen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/reifenlab.de\/mag\/so-messen-sie-das-reifenprofil-richtig-und-einfach\/#Ein_letzter_Rat\" title=\"Ein letzter Rat\">Ein letzter Rat<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Was_ist_vor_der_eigentlichen_Messung_zu_tun\"><\/span><strong>Was ist vor der eigentlichen Messung zu tun?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>F\u00fcr eine m\u00f6glichst genaue Messung ist es zun\u00e4chst erforderlich, das Fahrzeug auf einer ebenen Fl\u00e4che anzuhalten. Es ist ratsam, die Vorderr\u00e4der mit dem Lenkrad in den gr\u00f6\u00dftm\u00f6glichen Winkel zu drehen, damit wir besser an sie herankommen. Sobald das Auto bereit ist, versuchen wir, die Rillen der Lauffl\u00e4che an den Stellen, an denen wir die Tiefe messen wollen, von Schmutz zu befreien, sonst wird das Ergebnis logischerweise verf\u00e4lscht. Vor der Messung ist es auch ratsam, sich \u00fcber die geforderten Normen zu informieren, f\u00fcr Sommerreifen ist eine Mindestprofiltiefe von 1,6 mm und f\u00fcr Winterreifen eine Tiefe von 4 mm erforderlich.<a href=\"#_msocom_1\">[1]<\/a>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Laufflachenverschleisindikator_TWITread_Wear_indicator\"><\/span><strong>Lauffl\u00e4chenverschlei\u00dfindikator (TWI=Tread Wear indicator)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die einfachste M\u00f6glichkeit, einen abgefahrenen Reifen zu erkennen, ist der Blick auf den Reifen. Die Rillen in der Lauffl\u00e4che von Sommerreifen sind oft mit 1,6 mm dicken Gummipolstern ausgestattet, was das gesetzliche Minimum f\u00fcr PKWs ist. Sobald der Reifen bis zur vorgeschriebenen Grenze abgenutzt ist (die meisten Reifen haben einen Indikator, der sich in einer Tiefe von 1,6 mm befindet), wird das Polster parallel zum Rest des Reifens, was ein Zeichen f\u00fcr den Fahrer ist, dass der Reifen ersetzt werden muss. Sie k\u00f6nnen die Position des Verschlei\u00dfindikators anhand der Markierung finden, die sich in der N\u00e4he des Indikators auf der Seitenwand des Reifens befindet. Bei den Marken sind die am h\u00e4ufigsten verwendeten Symbole das Markenlogo, die Abk\u00fcrzung TWI (Tread Wear Indicator) oder ein Dreieck. Einige Winterreifen sind zus\u00e4tzlich mit einem Winterindikator in einer Tiefe von 4 mm ausgestattet. Achten Sie bei diesen auf ein Symbol in Form einer Schneeflocke an der Seite der Lauffl\u00e4che.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"1024\" src=\"https:\/\/www.thetirelab.com\/mag\/wp-content\/uploads\/2020\/12\/WP_20130420_007-615x1024.jpg\" alt=\"\" class=\"wp-image-57\" srcset=\"https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/WP_20130420_007-615x1024.jpg 615w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/WP_20130420_007-180x300.jpg 180w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/WP_20130420_007.jpg 767w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/><\/figure>\n\n\n\n<p><em>Einige Hersteller verwenden statt eines Pfeils oft auch das Wort &#8220;TWI&#8221; an der Seite. Dieses Bild zeigt einen Reifen, der bereits h\u00e4tte ausgetauscht werden m\u00fcssen, weil er sich dem gesetzlichen Grenzwert von 1,6 mm n\u00e4hert.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Numerische_Verschleisindikator\"><\/span><strong>Numerische Verschlei\u00dfindikator<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Der numerische Verschlei\u00dfindikator ist eine &#8220;verbesserte&#8221; Version des oben erw\u00e4hnten TWI-Indikators, der Ihnen die Profiltiefe anzeigt, ohne dass Sie diese mit einem speziellen Werkzeug messen m\u00fcssen. Die Zahlen zeigen die Tiefe des Reifens an und werden allm\u00e4hlich gel\u00f6scht, wenn der Reifen abgenutzt ist. Dies ist ein intelligentes System, das einfach und gleichzeitig sehr genau ist. Eine numerischer Verschlei\u00dfindikator ist jedoch nicht bei allen Marken anzutreffen, derzeit wird er z.B. von Nokian oder Matador verwendet. Bedenken Sie auch, dass es die Profiltiefe nur in der Mitte der Lauffl\u00e4che anzeigt &#8211; wenn Sie nicht den richtigen Reifendruck haben oder Ihr Auto Probleme mit der Ausrichtung hat, ist die Wahrscheinlichkeit gro\u00df, dass Ihre Reifen ungleichm\u00e4\u00dfig abgenutzt sind und ersetzt werden m\u00fcssen, obwohl in der Mitte der Lauffl\u00e4che noch gen\u00fcgend Profil vorhanden ist.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"356\" src=\"https:\/\/www.thetirelab.com\/mag\/wp-content\/uploads\/2020\/12\/hloubkadezenunokian.jpg\" alt=\"\" class=\"wp-image-58\" srcset=\"https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/hloubkadezenunokian.jpg 589w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/hloubkadezenunokian-300x181.jpg 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n\n\n\n<p><em>Profiltiefenindikator bei Nokian-Reifen &#8211; auf den ersten Blick ist erkennbar, dass noch ca. 6 mm Profil vorhanden sind<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tiefenmesser\"><\/span><strong>Tiefenmesser<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Der Tiefenmesser ist ein kleines Schiebewerkzeug, mit dem Sie das Profil an einzelnen Stellen der Lauffl\u00e4che genau analysieren k\u00f6nnen. Tiefenmessger\u00e4te k\u00f6nnen in jedem guten Autoservice oder Baumarkt gekauft werden und sie sind ziemlich billig (schlie\u00dflich ist es nur ein St\u00fcck Plastik mit Zahlen darauf), aber Sie k\u00f6nnen auch ein digitales Messger\u00e4t oder ein professionelles zertifiziertes Werkzeug bekommen, was teuer sein kann.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.thetirelab.com\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-3-768x1024.jpeg\" alt=\"\" class=\"wp-image-59\" srcset=\"https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-3-768x1024.jpeg 768w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-3-225x300.jpeg 225w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-3-1152x1536.jpeg 1152w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-3-1536x2048.jpeg 1536w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-3-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p><em>Ein einfacher und billiger Profiltiefenmesser funktioniert in den meisten F\u00e4llen gut<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Messung_mit_Munzen\"><\/span><strong>Messung mit M\u00fcnzen<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es gibt einen &#8220;Hack&#8221; f\u00fcr Fahrer, die keine anderen M\u00f6glichkeiten haben, die Profiltiefe zu messen &#8211; man kann eine M\u00fcnze verwenden. Wir stecken die M\u00fcnze in die Rille im Reifenprofil und je nachdem, wie tief die M\u00fcnze eindringt, bestimmen wir die Abnutzung des Reifens. Welche M\u00fcnze das ist, h\u00e4ngt wirklich von dem Land ab, in dem Sie sich befinden. In Gro\u00dfbritannien ist eine 20-Pence-M\u00fcnze am besten geeignet &#8211; wenn der \u00e4u\u00dfere Streifen der 20-Pence-M\u00fcnze beim Einstecken verdeckt wird, dann liegt Ihr Reifenprofil \u00fcber dem gesetzlichen Grenzwert.&nbsp; In EU-L\u00e4ndern kann auch eine 1-Euro-M\u00fcnze verwendet werden &#8211; wenn der Goldrand der M\u00fcnze zu sehen ist, ist Ihre Profiltiefe unter 3 mm und Sie sollten den Reifen idealerweise ersetzen.<em><\/em><\/p>\n\n\n\n<p>Bei Winterreifen, die h\u00f6here Anforderungen an die Profiltiefe stellen, wird eine 2-Euro-M\u00fcnze verwendet, wenn der \u00e4u\u00dfere Silberrand sichtbar ist, ist der Reifen abgefahren. Die Messung der Tiefe des M\u00fcnzbildes ist jedoch nicht ausreichend und kann einen Tiefenmesser nicht ersetzen, dies sind nur Richtwerte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.thetirelab.com\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-1024x576.jpeg\" alt=\"\" class=\"wp-image-60\" srcset=\"https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-1024x576.jpeg 1024w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-300x169.jpeg 300w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-768x432.jpeg 768w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-1536x864.jpeg 1536w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2020\/12\/Soubor_000-2048x1152.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>Dieser Reifen hat eine ausreichende Profiltiefe um 5 mm, ist aber ungleichm\u00e4\u00dfig abgefahren und sollte ersetzt werden<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ein_letzter_Rat\"><\/span><strong>Ein letzter Rat<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Experten sind sich einig, dass 1,6 mm als minimal zul\u00e4ssige Profiltiefe nicht ausreichen &#8211; viel sicherer ist es, die Reifen zu wechseln, wenn die Profiltiefe unter 3 mm f\u00e4llt. Unterhalb dieser Grenze verschlechtert sich die F\u00e4higkeit, Aquaplaning zu verhindern, rapide.&nbsp; Wir k\u00f6nnen einen Blick auf die Daten werfen, die Nokian zur Verf\u00fcgung gestellt hat:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Neuer Sommerreifen \u2013 7 mm<\/td><td>83.1 km\/h<\/td><\/tr><tr><td>Abgenutzter Sommerreifen 3-4 mm<\/td><td>61.2 km\/h<\/td><\/tr><tr><td>Abgenutzter Winterreifen 3 mm<\/td><td>60.3 km\/h<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><em>Anfangsgeschwindigkeit von Aquaplaning beim Fahren in einer Kurve<\/em><\/p>\n\n\n\n<p><strong>Auch pr\u00fcfen:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.off-road.de\/de\/service\/servicetipps\/archiv-service\/welche-reifenmarke-haelt-am-laengsten\/\">Welche Reifenmarke h\u00e4lt am l\u00e4ngsten?<\/a> &#8211; offroad.de<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend der Fahrt nutzt sich die Oberfl\u00e4che der Lauffl\u00e4che, je nach verwendeter Mischung, unterschiedlich schnell ab, sodass der Reifen nicht mehr den gesetzlichen Normen entspricht. Diese Normen wurden jedoch aus gutem Grund eingef\u00fchrt &#8211; ein abgenutzter Reifen hat eine schlechtere Haftung, einen l\u00e4ngeren Bremsweg und ist anf\u00e4lliger f\u00fcr Aquaplaning, daher ist die regelm\u00e4\u00dfige Kontrolle der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-67","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/posts\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/comments?post=67"}],"version-history":[{"count":6,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/posts\/67\/revisions"}],"predecessor-version":[{"id":84,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/posts\/67\/revisions\/84"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/media\/61"}],"wp:attachment":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/media?parent=67"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/categories?post=67"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/tags?post=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}