{"id":7167,"date":"2026-08-26T06:35:41","date_gmt":"2026-08-26T06:35:41","guid":{"rendered":"https:\/\/reifenlab.eu\/mag\/continental-zevra-konzeptreifen-verwendet-43-recycelte-materialien-und-erreicht-die-beste-eu-rollwiderstandsbewertung\/"},"modified":"2026-08-26T06:35:41","modified_gmt":"2026-08-26T06:35:41","slug":"continental-zevra-konzeptreifen-verwendet-43-recycelte-materialien-und-erreicht-die-beste-eu-rollwiderstandsbewertung","status":"publish","type":"post","link":"https:\/\/reifenlab.de\/mag\/continental-zevra-konzeptreifen-verwendet-43-recycelte-materialien-und-erreicht-die-beste-eu-rollwiderstandsbewertung\/","title":{"rendered":"Continental ZEvRA-Konzeptreifen verwendet 43% recycelte Materialien und erreicht die beste EU-Rollwiderstandsbewertung"},"content":{"rendered":"\n<p>Continental hat einen Konzeptreifen entwickelt, der rund 43% physisch recycelte Materialien enth\u00e4lt und zugleich die h\u00f6chste auf dem EU-Reifenlabel verf\u00fcgbare Rollwiderstandsbewertung erreicht. Das Ergebnis deutet darauf hin, dass eine geringere Abh\u00e4ngigkeit von neuen Rohstoffen nicht zwangsl\u00e4ufig die Energieeffizienz beeintr\u00e4chtigen muss, allerdings hat das Unternehmen nur einen begrenzten Umfang an Leistungsinformationen ver\u00f6ffentlicht.<\/p>\n\n\n\n<p>Der ZEvRA-Reifen bleibt ein Entwicklungsprojekt und ist kein Produkt, das f\u00fcr den unmittelbaren Verkauf bestimmt ist. Laut der <a href=\"https:\/\/www.continental.com\/en\/press\/press-releases\/eu-project-zevra\/\">Pressemitteilung von Continental<\/a> soll er zeigen, was sich durch die Kombination mehrerer Technologien f\u00fcr kreislauff\u00e4hige Materialien in einem Pkw-Reifen erreichen l\u00e4sst.<\/p>\n\n\n\n<p>\u201eUnser Konzeptreifen zeigt, was heute technisch m\u00f6glich ist \u2013 und dient zugleich als Katalysator f\u00fcr die Innovationen von morgen\u201c, sagte Dr Andreas Topp, bei Continental Leiter der Plattformentwicklung und Industrialisierung f\u00fcr Pkw-Reifen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/reifenlab.eu\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-concept-tyre-close-up.jpg\" alt=\"Nahaufnahme des Continental ZEvRA-Konzeptreifens mit ZEvRA-Logo und Profil\" class=\"wp-image-7163\" srcset=\"https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-concept-tyre-close-up.jpg 2000w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-concept-tyre-close-up-300x200.jpg 300w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-concept-tyre-close-up-1024x682.jpg 1024w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-concept-tyre-close-up-768x512.jpg 768w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-concept-tyre-close-up-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><figcaption class=\"wp-element-caption\">Foto: Continental<\/figcaption><\/figure>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_69_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\">\u2630<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a9885dee7d1a\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9885dee7d1a\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/reifenlab.de\/mag\/continental-zevra-konzeptreifen-verwendet-43-recycelte-materialien-und-erreicht-die-beste-eu-rollwiderstandsbewertung\/#Recycelter_Kautschuk_Stahl_PET_und_Giesereisand\" title=\"Recycelter Kautschuk, Stahl, PET und Gie\u00dfereisand\">Recycelter Kautschuk, Stahl, PET und Gie\u00dfereisand<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/reifenlab.de\/mag\/continental-zevra-konzeptreifen-verwendet-43-recycelte-materialien-und-erreicht-die-beste-eu-rollwiderstandsbewertung\/#Teil_eines_umfassenderen_EU-Kreislaufprojekts\" title=\"Teil eines umfassenderen EU-Kreislaufprojekts\">Teil eines umfassenderen EU-Kreislaufprojekts<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/reifenlab.de\/mag\/continental-zevra-konzeptreifen-verwendet-43-recycelte-materialien-und-erreicht-die-beste-eu-rollwiderstandsbewertung\/#Was_dies_fur_Reifenkaufer_bedeutet\" title=\"Was dies f\u00fcr Reifenk\u00e4ufer bedeutet\">Was dies f\u00fcr Reifenk\u00e4ufer bedeutet<\/a><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Recycelter_Kautschuk_Stahl_PET_und_Giesereisand\"><\/span>Recycelter Kautschuk, Stahl, PET und Gie\u00dfereisand<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Zu den von Continental genannten recycelten Ausgangsstoffen geh\u00f6ren Stahl, recyceltes Tall\u00f6l, aus Altreifen zur\u00fcckgewonnener Kautschuk und Polyesterfasern aus recycelten PET-Flaschen. Der Konzeptreifen verwendet au\u00dferdem durch Pyrolyse gewonnenen Industrieru\u00df und eine alternative Form von Silica, die mit recyceltem Gie\u00dfereisand hergestellt wird.<\/p>\n\n\n\n<p>Diese physisch recycelten Materialien sind von den anderen f\u00fcr den Reifen geltend gemachten Beschaffungskategorien zu unterscheiden. Rund 13% seiner Materialien sind erneuerbar, weitere 25% sind massenbilanzzertifiziert. Die Massenbilanz ist ein Buchf\u00fchrungssystem, das zertifizierte Rohstoffe Produkten innerhalb eines gemeinsamen Produktionsprozesses zurechnet; sie bedeutet nicht, dass der entsprechende Anteil eines bestimmten Reifens physisch aus recyceltem Material besteht. \u00dcber alle drei unterschiedlichen Kategorien hinweg meldet Continental einen Gesamtanteil von mehr als 80%.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Reifen- oder Portfolioma\u00dfnahme<\/th><th>Gemeldeter Anteil<\/th><th>Umfang<\/th><\/tr><\/thead><tbody><tr><td>ZEvRA-Konzept<\/td><td>Rund 43%<\/td><td>Physisch recycelte Materialien<\/td><\/tr><tr><td>ZEvRA-Konzept<\/td><td>Rund 13%<\/td><td>Erneuerbare Materialien<\/td><\/tr><tr><td>ZEvRA-Konzept<\/td><td>25%<\/td><td>Massenbilanzzertifizierte Materialien<\/td><\/tr><tr><td>ZEvRA-Konzept<\/td><td>Mehr als 80%<\/td><td>Kombinierte recycelte, erneuerbare und massenbilanzzertifizierte Quellen<\/td><\/tr><tr><td>Serienreifen UltraContact NXT<\/td><td>Bis zu 65%<\/td><td>Kombinierte erneuerbare, recycelte und massenbilanzzertifizierte Materialien<\/td><\/tr><tr><td>Reifenportfolio von Continental, 2025<\/td><td>28%<\/td><td>Eingekaufte erneuerbare und recycelte Produktionsmaterialien<\/td><\/tr><tr><td>Portfolioziel von Continental, 2030<\/td><td>Mindestens 40%<\/td><td>Eingekaufte erneuerbare und recycelte Produktionsmaterialien<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Quelle: Pressemitteilung von Continental, 25. August 2026. Die Kategorien verwenden unterschiedliche Definitionen und sollten nicht als austauschbar behandelt werden.<\/figcaption><\/figure>\n\n\n\n<p>Continental verwendet in seinem Werk Korbach bereits zur\u00fcckgewonnenen Industrieru\u00df in allen neu produzierten Vollreifen, haupts\u00e4chlich f\u00fcr Gabelstapler; diese Praxis wurde 2023 eingef\u00fchrt. Der ebenfalls 2023 eingef\u00fchrte, f\u00fcr den Stra\u00dfenverkehr zugelassene UltraContact NXT bietet einen Vergleichsma\u00dfstab aus der Serienproduktion, allerdings fasst sein angegebener Wert erneuerbare, recycelte und massenbilanzzertifizierte Ausgangsstoffe zusammen. Unser Hintergrundartikel untersucht ausf\u00fchrlicher, <a href=\"https:\/\/reifenlab.eu\/mag\/how-sustainable-are-modern-tyres\/\">wie nachhaltig moderne Reifen sind<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/reifenlab.eu\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-recycled-material-sidewall.jpg\" alt=\"Seitenwand des Continental ZEvRA-Konzeptreifens mit der Kennzeichnung Enth\u00e4lt recyceltes Material\" class=\"wp-image-7165\" srcset=\"https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-recycled-material-sidewall.jpg 2000w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-recycled-material-sidewall-300x200.jpg 300w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-recycled-material-sidewall-1024x682.jpg 1024w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-recycled-material-sidewall-768x512.jpg 768w, https:\/\/reifenlab.de\/mag\/wp-content\/uploads\/2026\/08\/continental-zevra-recycled-material-sidewall-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><figcaption class=\"wp-element-caption\">Foto: Continental<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Teil_eines_umfassenderen_EU-Kreislaufprojekts\"><\/span>Teil eines umfassenderen EU-Kreislaufprojekts<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Continental ist der einzige Reifenhersteller unter den 28 Partnern von ZEvRA, einem von der EU gef\u00f6rderten Programm, das sich mit der Kreislauff\u00e4higkeit entlang der Wertsch\u00f6pfungsketten leichter Elektrofahrzeuge befasst. Laut dem <a href=\"https:\/\/cordis.europa.eu\/project\/id\/101138034\">CORDIS-Projekteintrag<\/a> der Europ\u00e4ischen Kommission l\u00e4uft ZEvRA vom 1. Januar 2024 bis zum 31. Dezember 2026, hat Gesamtkosten und einen EU-Beitrag von \u20ac11,382,948.50 und soll Alternativen f\u00fcr mehr als 84% der in Fahrzeugen verwendeten Materialien entwickeln.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Was_dies_fur_Reifenkaufer_bedeutet\"><\/span>Was dies f\u00fcr Reifenk\u00e4ufer bedeutet<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ein geringerer Rollwiderstand kann die Energie reduzieren, die erforderlich ist, um ein Fahrzeug in Bewegung zu halten. Damit k\u00f6nnte die beste Labelbewertung f\u00fcr den Kraftstoffverbrauch und die Reichweite von Elektrofahrzeugen relevant sein. Eine einzelne Labelkategorie kann jedoch weder die Gesamtsicherheit noch den Komfort oder die Nutzungsdauer des Reifens belegen, und eine Konzeptdemonstration ist kein Nachweis daf\u00fcr, dass identische Materialien und Leistungen bald in den Verkaufsr\u00e4umen ankommen werden.<\/p>\n\n\n\n<p>Continental k\u00fcndigte weder eine Markteinf\u00fchrung noch ein Gr\u00f6\u00dfensortiment oder einen Preis an. Au\u00dferdem stellte das Unternehmen f\u00fcr das ZEvRA-Konzept keine vollst\u00e4ndigen Reifenlabelwerte, unabh\u00e4ngigen Testergebnisse, Nasshaftungsbewertung, Bewertung des externen Rollger\u00e4uschs oder Haltbarkeitsdaten bereit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continental hat einen Konzeptreifen entwickelt, der rund 43% physisch recycelte Materialien enth\u00e4lt und zugleich die h\u00f6chste auf dem EU-Reifenlabel verf\u00fcgbare Rollwiderstandsbewertung erreicht. Das Ergebnis deutet darauf hin, dass eine geringere Abh\u00e4ngigkeit von neuen Rohstoffen nicht zwangsl\u00e4ufig die Energieeffizienz beeintr\u00e4chtigen muss, allerdings hat das Unternehmen nur einen begrenzten Umfang an Leistungsinformationen ver\u00f6ffentlicht. Der ZEvRA-Reifen bleibt ein [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[204,31],"tags":[18,76],"class_list":["post-7167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-continental","category-novinky","tag-continental","tag-electric-vehicles"],"acf":[],"_links":{"self":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/posts\/7167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/comments?post=7167"}],"version-history":[{"count":0,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/posts\/7167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/media\/7164"}],"wp:attachment":[{"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/media?parent=7167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/categories?post=7167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reifenlab.de\/mag\/wp-json\/wp\/v2\/tags?post=7167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}